{"id":10452,"date":"2021-10-11T13:22:58","date_gmt":"2021-10-11T16:22:58","guid":{"rendered":"http:\/\/prd-cul-web04.vicentelopez.gov.ar\/evento\/adios-al-paraiso-copy\/"},"modified":"2023-11-17T15:52:37","modified_gmt":"2023-11-17T18:52:37","slug":"la-conmemoracion","status":"publish","type":"evento","link":"https:\/\/lumiton.ar\/en\/evento\/la-conmemoracion\/","title":{"rendered":"LA CONMEMORACI\u00d3N"},"content":{"rendered":"<p>Una semana antes de la 46\u00aa conmemoraci\u00f3n del Golpe de Estado, Miguel y Gast\u00f3n -dos electricistas- acuden al llamado de Victoria, la viuda de un ex agente de la CNI, quien les solicita arreglar el sistema el\u00e9ctrico de su casa. All\u00ed y por casualidad, encontraran un gran tesoro escondido en el s\u00f3tano. El \u00fanico problema es c\u00f3mo sacarlo sin que nadie lo note.<\/p>\n<p><em>*Disponible en Argentina.<\/em><\/p>\n","protected":false},"featured_media":9307,"template":"","tipo":[57,63],"class_list":["post-10452","evento","type-evento","status-publish","has-post-thumbnail","hentry","tipo-proyecciones","tipo-vecine-vecine"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento\/10452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media\/9307"}],"wp:attachment":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media?parent=10452"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/tipo?post=10452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}