{"id":12451,"date":"2022-04-28T00:51:37","date_gmt":"2022-04-28T03:51:37","guid":{"rendered":"http:\/\/prd-cul-web04.vicentelopez.gov.ar\/?post_type=evento&#038;p=12451"},"modified":"2023-08-01T14:59:38","modified_gmt":"2023-08-01T17:59:38","slug":"zaho-zay-georg-tiller-funcion-presencial","status":"publish","type":"evento","link":"https:\/\/lumiton.ar\/en\/evento\/zaho-zay-georg-tiller-funcion-presencial\/","title":{"rendered":"ZAHO ZAY &#8211; GEORG TILLER | FUNCI\u00d3N PRESENCIAL"},"content":{"rendered":"<p>Una joven trabaja como guardia en una prisi\u00f3n en Madagascar. Pasa el tiempo so\u00f1ando despierta con su padre, un asesino que la abandon\u00f3 de ni\u00f1a despu\u00e9s de matar a su propio hermano.<\/p>\n<h3>Foco WHY PLASTIC?<\/h3>\n<p>Why Plastic? es una serie de documentales de investigaci\u00f3n en tres partes que acabar\u00e1 con los mitos y la desinformaci\u00f3n, examinando de cerca lo que es realidad y lo que es ficci\u00f3n. Cada pel\u00edcula investiga un aspecto diferente de la contaminaci\u00f3n por pl\u00e1stico: El reciclaje, la salud humana y la industria. Creemos que la educaci\u00f3n c\u00edvica y el libre acceso a medios de comunicaci\u00f3n fiables es un paso fundamental para abordar los problemas sociales y lograr el cambio. El cine documental es una poderosa herramienta que ayuda a transmitir informaci\u00f3n importante y a difundir conocimientos. WHY PLASTIC? contribuir\u00e1 a crear un debate matizado y objetivo en torno a la contaminaci\u00f3n por pl\u00e1sticos y los problemas relacionados con ella, como la crisis clim\u00e1tica, la justicia medioambiental y la salud p\u00fablica.<\/p>\n<p>Proyecci\u00f3n de las 3 pel\u00edculas del Foco Why Plastic? + Mesa y coffe break + Feria del pl\u00e1stico en la Plaza frente al cine: de 14 a 19.30 hs.<\/p>\n<p><span style=\"font-weight: 400;\">Conversatorio: Econom\u00eda verde inclusiva, sostenible y resiliente: 17 hs.<\/span><\/p>\n","protected":false},"featured_media":12452,"template":"","tipo":[57,63,507],"class_list":["post-12451","evento","type-evento","status-publish","has-post-thumbnail","hentry","tipo-proyecciones","tipo-vecine-vecine","tipo-construir-cine"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento\/12451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media\/12452"}],"wp:attachment":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media?parent=12451"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/tipo?post=12451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}