{"id":16958,"date":"2022-05-02T13:01:11","date_gmt":"2022-05-02T16:01:11","guid":{"rendered":"http:\/\/prd-cul-web04.vicentelopez.gov.ar\/?post_type=evento&#038;p=16958"},"modified":"2023-08-01T14:57:56","modified_gmt":"2023-08-01T17:57:56","slug":"acoua","status":"publish","type":"evento","link":"https:\/\/lumiton.ar\/en\/evento\/acoua\/","title":{"rendered":"ACOUA"},"content":{"rendered":"<h3>COMPETENCIA CORTOMETRAJE ARGENTINO<\/h3>\n<p>\u00bfQu\u00e9 pasa si juntamos distintas clases sociales en una entrevista de trabajo? Una entra\u00f1able historia en la que personas de distintas clases sociales se encuentran en una entrevista de trabajo colectiva. Mostrar los valores que tiene el otro candidato har\u00e1 que puedan ser contratados o no.<\/p>\n<p>Bio de los directores<\/p>\n<p>G\u00dcIDO SIMONETTI<br \/>\nEs director, dramaturgo, guionista y actor. Entre sus trabajos se destacan cortometrajes como Acoua, El caso Q ,M\u00e1gica y mini series como Delta y La mesa de al lado.<\/p>\n<p>He is a director, playwright, screenwriter and actor. His work includes short films such as Acoua, El caso Q, M\u00e1gica and mini series such as Delta and La mesa de al lado.<\/p>\n<p>FABIAN BENITEZ<br \/>\nEs actor y director conocido por los cortometrajes\u00a0 Acoua y Sin c\u00f3digos.<\/p>\n<p>He is an actor and director known for the short films Acoua and Sin c\u00f3digos.<\/p>\n<p>G\u00fcido Simonetti \u2013 Director y Guionista<br \/>\n1 Premio Internacional a Mejor Pel\u00edcula Biogr\u00e1fica<br \/>\n3 Premios Internacionales a Mejor Cortometraje<br \/>\n5 Premios Nacionales a Mejor Cortometraje<br \/>\n4 Premios Internacionales a Mejor Serie Web<br \/>\n5 Premios del P\u00fablico a Mejor Cortometraje<br \/>\n1 Premio Internacional a Mejor Guion de Cortometraje<br \/>\n1 Premio Internacional a Mejor Formato Original en Series Web<br \/>\n1 Premio Internacional a Mejor Edici\u00f3n en Series Web<br \/>\n1 Nominaci\u00f3n Internacional a Mejor Pel\u00edcula<br \/>\n17 Nominaciones Internacionales a Mejor Cortometraje<br \/>\n17 Nominaciones Internacionales a Mejor Serie Web de Drama<br \/>\n7 Nominaciones Internacionales a Mejor Direcci\u00f3n en Series Web<br \/>\n5 Nominaciones Internacionales a Mejor Gui\u00f3n en Series Web<br \/>\n4 Nominaciones Internacionales a Mejor Elenco Actoral<br \/>\n3 Nominaciones Internacionales a Mejor Serie Web Extranjera<br \/>\n2 Nominaciones Nacionales a Mejor Serie Web de Drama<br \/>\n2 Nominaciones Internacionales a Mejor Fotograf\u00eda en Series Web<br \/>\n2 Nominaciones Internacionales a Mejor Formato Original en Series Web<br \/>\n1 Nominaci\u00f3n Internacional a Mejor Edici\u00f3n en Series Web<br \/>\nEscribi\u00f3 una de las pel\u00edculas mas taquilleras del cine Peruano (La Foquita)<\/p>\n<p>*Disponible en todo el mundo.<\/p>\n","protected":false},"featured_media":16979,"template":"","tipo":[57,63,507],"class_list":["post-16958","evento","type-evento","status-publish","has-post-thumbnail","hentry","tipo-proyecciones","tipo-vecine-vecine","tipo-construir-cine"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento\/16958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media\/16979"}],"wp:attachment":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media?parent=16958"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/tipo?post=16958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}