{"id":16966,"date":"2022-05-02T13:12:21","date_gmt":"2022-05-02T16:12:21","guid":{"rendered":"http:\/\/prd-cul-web04.vicentelopez.gov.ar\/?post_type=evento&#038;p=16966"},"modified":"2023-08-01T14:57:13","modified_gmt":"2023-08-01T17:57:13","slug":"fabian-canta","status":"publish","type":"evento","link":"https:\/\/lumiton.ar\/en\/evento\/fabian-canta\/","title":{"rendered":"FABI\u00c1N SINGS (FABI\u00c1N CANTA)"},"content":{"rendered":"<h3>COMPETENCIA CORTOMETRAJE ARGENTINO<\/h3>\n<p>Fabi\u00e1n atiende un sal\u00f3n de fiestas, ofrece shows de magos, bailarines y cantantes, entre los que se encuentra un tributo a Serrat. Eugenia, la nueva clienta, contrata una odalisca para el cumplea\u00f1os de su padre. Fabi\u00e1n, cansado de que nunca lo elijan, har\u00e1 lo imposible para que cambie de opini\u00f3n, aunque deba recurrir a t\u00e9cnicas inescrupulosas para desacreditar a su compa\u00f1era.<\/p>\n<p>Bio del director<\/p>\n<p>Naci\u00f3 en Buenos Aires, estudi\u00f3 periodismo en TEA y se desempe\u00f1\u00f3 como productor period\u00edstico en canales de TV. Se desarroll\u00f3 como guionista y director realiz\u00f3 series documentales y de ficci\u00f3n.<\/p>\n<p>Born in Buenos Aires, he studied journalism at TEA and worked as a journalist producer in TV channels. He developed as a scriptwriter and director of documentary and fiction series.<\/p>\n<p>Diego Crespo (Buenos Aires, 1977) estudi\u00f3 periodismo en TEA y se desempe\u00f1\u00f3 como productor period\u00edstico en Canal 9, Canal 13, TN. Realiz\u00f3 talleres de gui\u00f3n y dramaturgia con Mauricio Kart\u00fan y se desarroll\u00f3 como guionista para: Infinito, Discovery Channel, Playboy, Fox Sports, Dory Media, Paka Paka, Disney Channel, Claxson, Canal 7. Como director realiz\u00f3 series documentales y de ficci\u00f3n para History Channel, Canal Encuentro, TecTV, Fox Life, DeporTV. Con apoyo del INCAA guion\u00f3 y dirigi\u00f3 los documentales \u201cContrapelota\u201d y \u201cDolores\u201d.<\/p>\n<p>*Disponible en todo el mundo.<\/p>\n","protected":false},"featured_media":17010,"template":"","tipo":[57,63,507],"class_list":["post-16966","evento","type-evento","status-publish","has-post-thumbnail","hentry","tipo-proyecciones","tipo-vecine-vecine","tipo-construir-cine"],"acf":[],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento\/16966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/evento"}],"about":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/types\/evento"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media\/17010"}],"wp:attachment":[{"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/media?parent=16966"}],"wp:term":[{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/lumiton.ar\/en\/wp-json\/wp\/v2\/tipo?post=16966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}